{"id":624,"date":"2020-06-16T09:26:05","date_gmt":"2020-06-16T09:26:05","guid":{"rendered":"https:\/\/imcl.co.th\/%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/"},"modified":"2025-01-13T04:15:13","modified_gmt":"2025-01-13T04:15:13","slug":"%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99","status":"publish","type":"page","link":"https:\/\/imcl.co.th\/th\/","title":{"rendered":"\u0e1a\u0e49\u0e32\u0e19"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"624\" class=\"elementor elementor-624 elementor-7\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbe95b7 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"cbe95b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-199b765\" data-id=\"199b765\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e21cd7 elementor-widget elementor-widget-slider_revolution\" data-id=\"6e21cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"home-slider-1-1\" data-id=\"2\" id=\"SR7_2_1\" data-version=\"6.7.57\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_2_1-3\" data-key=\"3\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_2_1-3-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/04\/slide_01B.jpg\" alt=\"\" title=\"slide_01B\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-3-0\" class=\"sr7-layer\">Industrial Marketing Company Group<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-3-1\" class=\"sr7-layer\">SOLUTIONS PROVIDER<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-3-2\" class=\"sr7-layer\" srscsrc><a  itemprop=\"url\" href=\"https:\/\/imcl.co.th\/our-business-units\/\" target=\"_self\" data-hover-background-color=\"#FFFFFF\" data-hover-border-color=\"#ffffff\" data-hover-color=\"#232323\" class=\"qbutton  default\" style=\"color: #FFFFFF; border-color: #FFFFFF; \">Our Business Units<\/a><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_2_1-4\" data-key=\"4\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_2_1-4-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/02\/slide_02B.jpg\" alt=\"\" title=\"slide_02B\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-4-0\" class=\"sr7-layer\">Sanitizing Solutions<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-4-1\" class=\"sr7-layer\">CLEARWIN KOREA<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-4-2\" class=\"sr7-layer\" srscsrc><a  itemprop=\"url\" href=\"https:\/\/clearwinthailand.com\/\" target=\"_blank\" data-hover-background-color=\"#FFFFFF\" data-hover-border-color=\"#FFFFFF\" data-hover-color=\"#232323\" class=\"qbutton  default\" style=\"color: #FFFFFF; border-color: #FFFFFF; \">Clearwin Korea Microsite<\/a><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_2_1-5\" data-key=\"5\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_2_1-5-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/02\/slide_03B.jpg\" alt=\"\" title=\"slide_03B\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-5-0\" class=\"sr7-layer\">Retail Solutions<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-5-1\" class=\"sr7-layer\">NEDAP RFID<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-5-2\" class=\"sr7-layer\" srscsrc><a  itemprop=\"url\" href=\"https:\/\/nedapthailand.com\/\" target=\"_blank\" data-hover-background-color=\"#FFFFFF\" data-hover-border-color=\"#FFFFFF\" data-hover-color=\"#232323\" class=\"qbutton  default\" style=\"color: #FFFFFF; border-color: #FFFFFF; \">Nedap Thailand Microsite<\/a><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_2_1-6\" data-key=\"6\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_2_1-6-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/02\/slide_04B.jpg\" alt=\"\" title=\"slide_04B\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-6-0\" class=\"sr7-layer\">High Quality & Durable Powertool Accessories<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-6-1\" class=\"sr7-layer\">SUTTON TOOLS<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-6-2\" class=\"sr7-layer\" srscsrc><a  itemprop=\"url\" href=\"https:\/\/suttontoolsthailand.com\/\" target=\"_blank\" data-hover-background-color=\"#FFFFFF\" data-hover-border-color=\"#FFFFFF\" data-hover-color=\"#232323\" class=\"qbutton  default\" style=\"color: #FFFFFF; border-color: #FFFFFF; \">Sutton Tools Thailand Microsite<\/a><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_2_1-7\" data-key=\"7\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_2_1-7-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/02\/slide_05B.jpg\" alt=\"\" title=\"slide_05B\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-7-0\" class=\"sr7-layer\">Quality Laser Tool<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-7-1\" class=\"sr7-layer\">ACCULASER<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-7-2\" class=\"sr7-layer\" srscsrc><a  itemprop=\"url\" href=\"https:\/\/acculaser.co.th\/\" target=\"_blank\" data-hover-background-color=\"#FFFFFF\" data-hover-border-color=\"#FFFFFF\" data-hover-color=\"#232323\" class=\"qbutton  default\" style=\"color: #FFFFFF; border-color: #FFFFFF; \">Acculaser Microsite<\/a><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_2_1-8\" data-key=\"8\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_2_1-8-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/02\/slide_06.jpg\" alt=\"\" title=\"slide_06\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-8-0\" class=\"sr7-layer\">ODOR CONTROL SOLUTIONS<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-8-1\" class=\"sr7-layer\">WALEX USA<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_2_1-8-2\" class=\"sr7-layer\" srscsrc><a  itemprop=\"url\" href=\"https:\/\/walexthailand.com\/\" target=\"_blank\" data-hover-background-color=\"#FFFFFF\" data-hover-border-color=\"#FFFFFF\" data-hover-color=\"#232323\" class=\"qbutton  default\" style=\"color: #FFFFFF; border-color: #FFFFFF; \">Walex Thailand Microsite<\/a><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_2_1-10\" data-key=\"10\">\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\twindow.SR7 ??={};SR7.PMH ??={}; SR7.PMH[\"SR7_2_1\"] = {cn:100,state:false,fn: function() { if (window._tpt!==undefined && window._tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_2_1\",el:[900,768,960,720],type:'standard',shdw:'0',gh:[900,768,960,720],gw:[1240,1024,778,480],vpt:['-200px'],size:{fullWidth:true, fullHeight:true},offsetContainer:'',offset:'',mh:'0',onh:0,onw:0,bg:{color:'#b5c6cd'}});   SR7.PMH[\"SR7_2_1\"].state=true;} else if(SR7.PMH[\"SR7_2_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_2_1\"].fn,19);}};SR7.PMH[\"SR7_2_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2cd001 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"b2cd001\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-647b8ac\" data-id=\"647b8ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d39b42b elementor-widget elementor-widget-image\" data-id=\"d39b42b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2500\" height=\"1065\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1.jpg\" class=\"attachment-full size-full wp-image-596\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1.jpg 2500w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1-300x128.jpg 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1-1024x436.jpg 1024w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1-768x327.jpg 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1-1536x654.jpg 1536w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1-2048x872.jpg 2048w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/industrial-marketing-1-700x298.jpg 700w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-26f0b9e\" data-id=\"26f0b9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-685a448 elementor-widget elementor-widget-text-editor\" data-id=\"685a448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19<\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9956f7 elementor-widget elementor-widget-text-editor\" data-id=\"f9956f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01<\/h1>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ace3f17 elementor-widget elementor-widget-text-editor\" data-id=\"ace3f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Industrial Marketing \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e40\u0e0a\u0e48\u0e19 Kapro Levels \u0e08\u0e32\u0e01\u0e2d\u0e34\u0e2a\u0e23\u0e32\u0e40\u0e2d\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 Sutton Tools \u0e08\u0e32\u0e01\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d UV-C \u0e08\u0e32\u0e01 Clearwin Korea \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 RFID \u0e08\u0e32\u0e01 Nedap<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-462d066 elementor-widget elementor-widget-bridge_button\" data-id=\"462d066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"https:\/\/imcl.co.th\/our-business-units\/\" target=\"_self\"  class=\"qbutton  default\" style=\"\">\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5abde31 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"5abde31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25ce74f\" data-id=\"25ce74f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b5f27b elementor-widget elementor-widget-bridge_carousel\" data-id=\"0b5f27b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='qode_carousels_holder clearfix'><div class='qode_carousels' data-number-of-visible-items=''><ul class='slides'>Sorry, no posts matched your criteria.<\/ul><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1645b12 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"1645b12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e74092\" data-id=\"6e74092\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c63894 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"6c63894\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-adb385a\" data-id=\"adb385a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1616373\" data-id=\"1616373\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6f3501 elementor-widget elementor-widget-image\" data-id=\"c6f3501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1225\" height=\"825\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/985T_apl.jpg\" class=\"attachment-full size-full wp-image-597\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/985T_apl.jpg 1225w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/985T_apl-300x202.jpg 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/985T_apl-1024x690.jpg 1024w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/985T_apl-768x517.jpg 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/985T_apl-700x471.jpg 700w\" sizes=\"(max-width: 1225px) 100vw, 1225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b40b18b elementor-widget elementor-widget-text-editor\" data-id=\"b40b18b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e25\u0e22\u0e4c\u0e40\u0e2d\u0e32\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e32\u0e42\u0e1b\u0e23<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa2bf8 elementor-widget elementor-widget-text-editor\" data-id=\"6aa2bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kapro Industries Ltd. \u0e44\u0e14\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32 30 \u0e1b\u0e35<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c14f9e elementor-widget elementor-widget-bridge_button_v2\" data-id=\"3c14f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<a href=\"https:\/\/kaprothailand.com\" target=\"_blank\"  class=\"qode-btn qode-btn-medium qode-btn-simple\"  >\n\t    <span class=\"qode-btn-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-94418cc\" data-id=\"94418cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebbf9ea elementor-widget elementor-widget-image\" data-id=\"ebbf9ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1224\" height=\"825\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/iL33-MainEntrance-007.jpg\" class=\"attachment-full size-full wp-image-598\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/iL33-MainEntrance-007.jpg 1224w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/iL33-MainEntrance-007-300x202.jpg 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/iL33-MainEntrance-007-1024x690.jpg 1024w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/iL33-MainEntrance-007-768x518.jpg 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/iL33-MainEntrance-007-700x472.jpg 700w\" sizes=\"(max-width: 1224px) 100vw, 1224px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-921e9fd elementor-widget elementor-widget-text-editor\" data-id=\"921e9fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 NEDAP<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09ab02e elementor-widget elementor-widget-text-editor\" data-id=\"09ab02e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e08\u0e19\u0e16\u0e36\u0e07\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 RFID \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2591c57 elementor-widget elementor-widget-bridge_button_v2\" data-id=\"2591c57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<a href=\"https:\/\/nedapthailand.com\" target=\"_blank\"  class=\"qode-btn qode-btn-medium qode-btn-simple\"  >\n\t    <span class=\"qode-btn-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-53a7ed7\" data-id=\"53a7ed7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6819a5 elementor-widget elementor-widget-image\" data-id=\"b6819a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1225\" height=\"825\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/clearwin-parq.jpg\" class=\"attachment-full size-full wp-image-599\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/clearwin-parq.jpg 1225w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/clearwin-parq-300x202.jpg 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/clearwin-parq-1024x690.jpg 1024w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/clearwin-parq-768x517.jpg 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/03\/clearwin-parq-700x471.jpg 700w\" sizes=\"(max-width: 1225px) 100vw, 1225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94d474e elementor-widget elementor-widget-text-editor\" data-id=\"94d474e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 UV-C<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-521536e elementor-widget elementor-widget-text-editor\" data-id=\"521536e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e43\u0e19\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e19\u0e35\u0e49 \u0e22\u0e38\u0e04 COVID \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 UV-C \u0e02\u0e2d\u0e07 Clearwin Korea \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e21\u0e32\u0e01<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee0ae25 elementor-widget elementor-widget-bridge_button_v2\" data-id=\"ee0ae25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<a href=\"https:\/\/clearwinthailand.com\" target=\"_blank\"  class=\"qode-btn qode-btn-medium qode-btn-simple\"  >\n\t    <span class=\"qode-btn-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf37182 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"bf37182\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05a7c75\" data-id=\"05a7c75\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c2e1a4 elementor-widget__width-auto elementor-widget elementor-widget-bridge_video_box\" data-id=\"4c2e1a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_video_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode_video_box disabled_hover_overlay disabled_hover_zoom\">\n\t<a itemprop=\"image\" class=\"qode_video_image\" href=\"https:\/\/www.youtube.com\/watch?v=ise-wDIekQ4\" data-rel=\"prettyPhoto\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"102\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2020\/06\/video-box-2.png\" class=\"attachment-full size-full\" alt=\"m\" \/>\t\t\t<span class=\"qode_video_box_button_holder\">\n\t\t\t\t<span class=\"qode_video_box_button\">\n\t\t\t\t\t<span class=\"qode_video_box_button_arrow\">\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/span>\n\t\t\t<\/a>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3447255 elementor-widget elementor-widget-text-editor\" data-id=\"3447255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/span><\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c0cbe5 elementor-widget elementor-widget-text-editor\" data-id=\"2c0cbe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e21\u0e49\u0e27\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 KAPRO 510<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-585a6ea elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"585a6ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-02e150c\" data-id=\"02e150c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d17751 elementor-widget elementor-widget-image\" data-id=\"4d17751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"550\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/toilet_lineup_walex.jpg\" class=\"attachment-large size-large wp-image-579\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/toilet_lineup_walex.jpg 801w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/toilet_lineup_walex-300x206.jpg 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/toilet_lineup_walex-768x527.jpg 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/toilet_lineup_walex-700x481.jpg 700w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb94794 elementor-widget elementor-widget-text-editor\" data-id=\"eb94794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e27\u0e32\u0e40\u0e25\u0e47\u0e01\u0e0b\u0e4c<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7f8de4 elementor-widget elementor-widget-text-editor\" data-id=\"c7f8de4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Walex \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e08\u0e32\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-548ab33 elementor-widget elementor-widget-bridge_button_v2\" data-id=\"548ab33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<a href=\"https:\/\/walexthailand.com\" target=\"_blank\"  class=\"qode-btn qode-btn-medium qode-btn-simple\"  >\n\t    <span class=\"qode-btn-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c788a44\" data-id=\"c788a44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-737341d elementor-widget elementor-widget-image\" data-id=\"737341d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"550\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/D101_Tipa.jpg\" class=\"attachment-large size-large wp-image-580\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/D101_Tipa.jpg 800w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/D101_Tipa-300x206.jpg 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/D101_Tipa-768x528.jpg 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/D101_Tipa-700x481.jpg 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a828cf2 elementor-widget elementor-widget-text-editor\" data-id=\"a828cf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0b\u0e31\u0e15\u0e15\u0e31\u0e19<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01801b8 elementor-widget elementor-widget-text-editor\" data-id=\"01801b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sutton Tools \u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e43\u0e19\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e15\u0e31\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2037feb elementor-widget elementor-widget-bridge_button_v2\" data-id=\"2037feb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<a href=\"https:\/\/suttontoolsthailand.com\" target=\"_blank\"  class=\"qode-btn qode-btn-medium qode-btn-simple\"  >\n\t    <span class=\"qode-btn-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-43f0e96\" data-id=\"43f0e96\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76ee060 elementor-widget elementor-widget-image\" data-id=\"76ee060\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"550\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/RFID-accelerateb.png\" class=\"attachment-large size-large wp-image-581\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/RFID-accelerateb.png 800w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/RFID-accelerateb-300x206.png 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/RFID-accelerateb-768x528.png 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/RFID-accelerateb-700x481.png 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a21a2b2 elementor-widget elementor-widget-text-editor\" data-id=\"a21a2b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u0e40\u0e2d\u0e1f\u0e2d\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e650f5 elementor-widget elementor-widget-text-editor\" data-id=\"8e650f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FE Technologies \u0e44\u0e14\u0e49\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e08\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c RFID \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c RFID \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07 Invengo International<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-964ea95 elementor-widget elementor-widget-bridge_button_v2\" data-id=\"964ea95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<a href=\"https:\/\/fetechnologiesthailand.com\" target=\"_blank\"  class=\"qode-btn qode-btn-medium qode-btn-simple\"  >\n\t    <span class=\"qode-btn-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4e72724\" data-id=\"4e72724\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa690a6 elementor-widget elementor-widget-image\" data-id=\"fa690a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"550\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/Installations_Fusion_1_highb-1.jpg\" class=\"attachment-large size-large wp-image-582\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/Installations_Fusion_1_highb-1.jpg 800w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/Installations_Fusion_1_highb-1-300x206.jpg 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/Installations_Fusion_1_highb-1-768x528.jpg 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2023\/01\/Installations_Fusion_1_highb-1-700x481.jpg 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f37fd37 elementor-widget elementor-widget-text-editor\" data-id=\"f37fd37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u0e40\u0e01\u0e15\u0e40\u0e27\u0e22\u0e4c<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28ee15f elementor-widget elementor-widget-text-editor\" data-id=\"28ee15f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gateway Security \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e42\u0e21\u0e17\u0e32\u0e25\u0e48\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e27\u0e35\u0e40\u0e14\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e2a\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e17\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e09\u0e25\u0e32\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e2b\u0e32\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e38\u0e48\u0e21\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e19\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43278e5 elementor-widget elementor-widget-bridge_button_v2\" data-id=\"43278e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<a href=\"#\" target=\"_self\"  class=\"qode-btn qode-btn-medium qode-btn-simple\"  >\n\t    <span class=\"qode-btn-text\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0db0a0c elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"0db0a0c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-362a8a8\" data-id=\"362a8a8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-706fa6a elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"706fa6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b206524\" data-id=\"b206524\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7a0db6 elementor-widget elementor-widget-text-editor\" data-id=\"c7a0db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd3a79 elementor-widget elementor-widget-text-editor\" data-id=\"4fd3a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15<\/h1>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca7143f elementor-widget elementor-widget-text-editor\" data-id=\"ca7143f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e23\u0e32\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e42\u0e14\u0e22\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e25\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f059e8 elementor-widget elementor-widget-bridge_button\" data-id=\"9f059e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"#\" target=\"_self\"  class=\"qbutton  default\" style=\"\">\u0e14\u0e39\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e6a88a3\" data-id=\"e6a88a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3c7743 elementor-widget elementor-widget-image\" data-id=\"c3c7743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1153\" height=\"784\" src=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2025\/01\/Business-partner_0.png\" class=\"attachment-full size-full wp-image-621\" alt=\"\" srcset=\"https:\/\/imcl.co.th\/wp-content\/uploads\/2025\/01\/Business-partner_0.png 1153w, https:\/\/imcl.co.th\/wp-content\/uploads\/2025\/01\/Business-partner_0-300x204.png 300w, https:\/\/imcl.co.th\/wp-content\/uploads\/2025\/01\/Business-partner_0-1024x696.png 1024w, https:\/\/imcl.co.th\/wp-content\/uploads\/2025\/01\/Business-partner_0-768x522.png 768w, https:\/\/imcl.co.th\/wp-content\/uploads\/2025\/01\/Business-partner_0-700x476.png 700w\" sizes=\"(max-width: 1153px) 100vw, 1153px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 Industr&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-624","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/pages\/624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/comments?post=624"}],"version-history":[{"count":2,"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/pages\/624\/revisions"}],"predecessor-version":[{"id":630,"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/pages\/624\/revisions\/630"}],"wp:attachment":[{"href":"https:\/\/imcl.co.th\/th\/wp-json\/wp\/v2\/media?parent=624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}